{"id":756,"date":"2025-12-17T08:30:37","date_gmt":"2025-12-17T07:30:37","guid":{"rendered":"https:\/\/baden-developpement.org\/?p=756"},"modified":"2025-12-17T08:32:56","modified_gmt":"2025-12-17T07:32:56","slug":"abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus","status":"publish","type":"post","link":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/","title":{"rendered":"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fid\u00e8le \u00e0 sa volont\u00e9 de transparence sur ses travaux, ABD publie aujourd\u2019hui ses estimations d\u00e9taill\u00e9es pour le projet <strong>complet<\/strong> de P\u00f4le Sportif \u00e0 Kergonano et pour le projet <strong>complet<\/strong> de r\u00e9novation du Tumulus avec les extensions pour la danse, le judo et le basket 3&#215;3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le r\u00e9sultat de ces estimations est tr\u00e8s clair&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le projet complet de P\u00f4le Sportif \u00e0 Kergonano est estim\u00e9 \u00e0 <strong>9.85 M\u20ac TTC<\/strong><\/li>\n\n\n\n<li>Le projet complet de r\u00e9novation et extension du Tumulus est estim\u00e9 \u00e0\u00a0<strong>4.08 M\u20ac TTC<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces estimations ont \u00e9t\u00e9 r\u00e9alis\u00e9es de mani\u00e8re ind\u00e9pendante par les membres du Conseil d\u2019Administration de ABD qui ont l\u2019exp\u00e9rience des travaux publics, avec l\u2019aide d\u2019un outil d\u2019estimation utilis\u00e9 pour les march\u00e9s publics et de comparaisons d\u00e9taill\u00e9es avec d\u2019autres projets de r\u00e9novation de salles omnisports dans la r\u00e9gion Bretagne. Les estimations incluent les \u00e9tudes, les travaux de construction, les \u00e9quipements sportifs et non sportifs, les travaux de parach\u00e8vement et de voirie ainsi que les co\u00fbts de d\u00e9construction de salles en d\u00e9but de projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ABD d\u00e9montre ainsi que le projet complet de r\u00e9novation et extension du Tumulus <strong>est \u00e9gal<\/strong> <strong>\u00e0 41%<\/strong>&nbsp; du projet complet de p\u00f4le sportif \u00e0 Kergonano, que l\u2019on chiffre en TTC ou en HT<strong>. Soit moins de la moiti\u00e9 du co\u00fbt total du projet Kergonano<\/strong>. Et ce pour le m\u00eame niveau fonctionnel offert aux sportifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ABD souligne que les activit\u00e9s <strong>non sportives<\/strong> (telles que march\u00e9 des cr\u00e9ateurs, march\u00e9 de No\u00ebl, forum des associations etc) sont <strong>interdites<\/strong> dans le projet de P\u00f4le Sportif&nbsp;\u2013 <em>ceci est clairement mentionn\u00e9 dans le permis de construire <\/em>\u2013 alors qu\u2019elles restent autoris\u00e9es dans le projet de r\u00e9novation du Tumulus. La proximit\u00e9 des \u00e9coles avec le Tumulus \u00e9vite \u00e9galement des surco\u00fbts de navette pour les \u00e9coliers ou encore les dangers de la marche et le temps perdu entre les \u00e9coles et le P\u00f4le Sportif.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ABD note \u00e9galement que le plan de financement et les estimations de frais de fonctionnement associ\u00e9s au projet de P\u00f4le Sportif n\u2019ont jamais \u00e9t\u00e9 publi\u00e9s par la Mairie.<br>Enfin, ABD rappelle que le projet de r\u00e9novation du Tumulus \u00e9tait au programme de la majorit\u00e9 municipale en 2020 mais que aucun projet ou avant-projet n\u2019a \u00e9t\u00e9 mis en \u0153uvre par la Mairie pendant toute la mandature.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">______________________________________________________________________________________________________<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>En conclusion, ABD persiste et signe<\/strong>&nbsp;:&nbsp;<br>Sur les aspects financiers, fonctionnels, environnement, utilisation, le projet de r\u00e9novation et extension du Tumulus est bien plus pertinent pour la commune de Baden &#8211; sportifs, non sportifs et \u00e9coliers inclus.&nbsp; ABD demande donc la <strong>mise en \u00ab&nbsp;pause&nbsp;\u00bb<\/strong> du projet Kergonano pendant la p\u00e9riode \u00e9lectorale et l\u2019\u00e9tude des recours.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>L\u2019annulation du Sch\u00e9ma de Coh\u00e9rence Territoriale (SCoT) de GMVA le 15 d\u00e9cembre<\/strong> ne fait que renforcer notre position. Ce jugement d\u00e9finitif du Conseil d\u2019Etat est particuli\u00e8rement s\u00e9v\u00e8re et oblige GMVA \u00e0 revoir ce document d\u2019importance majeure, notamment pour le PLU de Baden, en ce qui concerne les zones \u00e0 urbaniser et la pr\u00e9servation des sites et espaces naturels. ABD rappelle que ce r\u00e9sultat est d\u00fb \u00e0 l\u2019action de l\u2019association des Amis des chemins de ronde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">_____________________________________________________________________________________________________<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9tail des estimations ABD pour chacun des projets complets est disponible sur les liens suivants&nbsp;<em>(via le site de lecture Calam\u00e9o):<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P\u00f4le sportif de Kergonano\u00a0\u00a0 <a href=\"https:\/\/www.calameo.com\/read\/007725888faf998980ef8\">https:\/\/www.calameo.com\/read\/007725888faf998980ef8<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9novation + Extension du Tumulus\u00a0 \u00a0\u00a0<a href=\"https:\/\/www.calameo.com\/read\/007725888bbd0cc769dde\">https:\/\/www.calameo.com\/read\/007725888bbd0cc769dde<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ABD profite de cette communication pour remercier tous les Badennoises et Badennois qui ont particip\u00e9 en nombre \u00e0 notre manifestation du 8 d\u00e9cembre au soir sur le parvis de la Mairie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une photo souvenir a \u00e9t\u00e9 publi\u00e9e par le T\u00e9l\u00e9gramme. Une autre est propos\u00e9e par Patrice Ruyssen.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Nous vous souhaitons de bonnes f\u00eates de fin d\u2019ann\u00e9e et vous disons \u00ab&nbsp;\u00e0 bient\u00f4t&nbsp;\u00bb&nbsp;!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"643\" src=\"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-1024x643.jpg\" alt=\"\" class=\"wp-image-758\" style=\"aspect-ratio:1.5925585804425748;width:460px;height:auto\" srcset=\"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-1024x643.jpg 1024w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-300x188.jpg 300w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-768x482.jpg 768w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-1536x965.jpg 1536w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-1140x716.jpg 1140w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-1320x829.jpg 1320w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25.jpg 1989w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-768x1024.jpg\" alt=\"\" class=\"wp-image-759\" style=\"width:312px;height:auto\" srcset=\"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-768x1024.jpg 768w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-225x300.jpg 225w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-1152x1536.jpg 1152w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-1536x2048.jpg 1536w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-1140x1520.jpg 1140w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-1320x1760.jpg 1320w, https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fid\u00e8le \u00e0 sa volont\u00e9 de transparence sur ses travaux, ABD publie aujourd\u2019hui ses estimations d\u00e9taill\u00e9es pour le projet complet de P\u00f4le Sportif \u00e0 Kergonano et pour le projet complet de r\u00e9novation du Tumulus avec les extensions pour la danse, le judo et le basket 3&#215;3.\u00a0<\/p>\n<p>Le r\u00e9sultat de ces estimations est tr\u00e8s clair\u00a0: le projet complet de P\u00f4le Sportif \u00e0 Kergonano est estim\u00e9 \u00e0 9.85 M\u20ac TTC; le projet complet de r\u00e9novation et extension du Tumulus est estim\u00e9 \u00e0\u00a04.08 M\u20ac TTC &#8230;.<\/p>\n","protected":false},"author":3,"featured_media":759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0! - Association Baden D\u00e9veloppement<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0! - Association Baden D\u00e9veloppement\" \/>\n<meta property=\"og:description\" content=\"Fid\u00e8le \u00e0 sa volont\u00e9 de transparence sur ses travaux, ABD publie aujourd\u2019hui ses estimations d\u00e9taill\u00e9es pour le projet complet de P\u00f4le Sportif \u00e0 Kergonano et pour le projet complet de r\u00e9novation du Tumulus avec les extensions pour la danse, le judo et le basket 3x3.\u00a0 Le r\u00e9sultat de ces estimations est tr\u00e8s clair\u00a0: le projet complet de P\u00f4le Sportif \u00e0 Kergonano est estim\u00e9 \u00e0 9.85 M\u20ac TTC; le projet complet de r\u00e9novation et extension du Tumulus est estim\u00e9 \u00e0\u00a04.08 M\u20ac TTC ....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/\" \/>\n<meta property=\"og:site_name\" content=\"Association Baden D\u00e9veloppement\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-17T07:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T07:32:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Denis Sempere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Denis Sempere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/\"},\"author\":{\"name\":\"Denis Sempere\",\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#\\\/schema\\\/person\\\/8b73b426699bc182dc9f25bed1f1c8c1\"},\"headline\":\"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0!\",\"datePublished\":\"2025-12-17T07:30:37+00:00\",\"dateModified\":\"2025-12-17T07:32:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/\"},\"wordCount\":705,\"commentCount\":2,\"publisher\":{\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/baden-developpement.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/manif-8-12-25-photo-2-scaled.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/\",\"url\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/\",\"name\":\"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0! - Association Baden D\u00e9veloppement\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/baden-developpement.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/manif-8-12-25-photo-2-scaled.jpg\",\"datePublished\":\"2025-12-17T07:30:37+00:00\",\"dateModified\":\"2025-12-17T07:32:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/baden-developpement.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/manif-8-12-25-photo-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/baden-developpement.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/manif-8-12-25-photo-2-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/2025\\\/12\\\/17\\\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/baden-developpement.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0!\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#website\",\"url\":\"http:\\\/\\\/baden-developpement.org\\\/\",\"name\":\"Association Baden D\u00e9veloppement\",\"description\":\"Demain se construit aujourd&#039;hui\",\"publisher\":{\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/baden-developpement.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#organization\",\"name\":\"Association Baden D\u00e9veloppement\",\"url\":\"http:\\\/\\\/baden-developpement.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/baden-developpement.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo_abd_rc_tr.png\",\"contentUrl\":\"https:\\\/\\\/baden-developpement.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo_abd_rc_tr.png\",\"width\":1051,\"height\":623,\"caption\":\"Association Baden D\u00e9veloppement\"},\"image\":{\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/baden-developpement.org\\\/#\\\/schema\\\/person\\\/8b73b426699bc182dc9f25bed1f1c8c1\",\"name\":\"Denis Sempere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cee0fe0e0dbe0a55cf3786d35daa256aa7a1b2802fe1a74406aebb920d6d763?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cee0fe0e0dbe0a55cf3786d35daa256aa7a1b2802fe1a74406aebb920d6d763?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cee0fe0e0dbe0a55cf3786d35daa256aa7a1b2802fe1a74406aebb920d6d763?s=96&d=mm&r=g\",\"caption\":\"Denis Sempere\"},\"url\":\"https:\\\/\\\/baden-developpement.org\\\/index.php\\\/author\\\/denis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0! - Association Baden D\u00e9veloppement","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/","og_locale":"fr_FR","og_type":"article","og_title":"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0! - Association Baden D\u00e9veloppement","og_description":"Fid\u00e8le \u00e0 sa volont\u00e9 de transparence sur ses travaux, ABD publie aujourd\u2019hui ses estimations d\u00e9taill\u00e9es pour le projet complet de P\u00f4le Sportif \u00e0 Kergonano et pour le projet complet de r\u00e9novation du Tumulus avec les extensions pour la danse, le judo et le basket 3x3.\u00a0 Le r\u00e9sultat de ces estimations est tr\u00e8s clair\u00a0: le projet complet de P\u00f4le Sportif \u00e0 Kergonano est estim\u00e9 \u00e0 9.85 M\u20ac TTC; le projet complet de r\u00e9novation et extension du Tumulus est estim\u00e9 \u00e0\u00a04.08 M\u20ac TTC ....","og_url":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/","og_site_name":"Association Baden D\u00e9veloppement","article_published_time":"2025-12-17T07:30:37+00:00","article_modified_time":"2025-12-17T07:32:56+00:00","og_image":[{"width":1920,"height":2560,"url":"http:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg","type":"image\/jpeg"}],"author":"Denis Sempere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Denis Sempere","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#article","isPartOf":{"@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/"},"author":{"name":"Denis Sempere","@id":"http:\/\/baden-developpement.org\/#\/schema\/person\/8b73b426699bc182dc9f25bed1f1c8c1"},"headline":"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0!","datePublished":"2025-12-17T07:30:37+00:00","dateModified":"2025-12-17T07:32:56+00:00","mainEntityOfPage":{"@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/"},"wordCount":705,"commentCount":2,"publisher":{"@id":"http:\/\/baden-developpement.org\/#organization"},"image":{"@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#primaryimage"},"thumbnailUrl":"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/","url":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/","name":"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0! - Association Baden D\u00e9veloppement","isPartOf":{"@id":"http:\/\/baden-developpement.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#primaryimage"},"image":{"@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#primaryimage"},"thumbnailUrl":"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg","datePublished":"2025-12-17T07:30:37+00:00","dateModified":"2025-12-17T07:32:56+00:00","breadcrumb":{"@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#primaryimage","url":"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg","contentUrl":"https:\/\/baden-developpement.org\/wp-content\/uploads\/2025\/12\/manif-8-12-25-photo-2-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/baden-developpement.org\/index.php\/2025\/12\/17\/abd-publie-ses-estimations-financieres-independantes-le-pole-sportif-de-kergonano-coute-pres-de-6-me-de-plus-que-la-renovation-extension-du-tumulus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/baden-developpement.org\/"},{"@type":"ListItem","position":2,"name":"ABD publie ses estimations financi\u00e8res ind\u00e9pendantes\u00a0: le p\u00f4le sportif de Kergonano co\u00fbte pr\u00e8s de 6 M\u20ac de plus que la r\u00e9novation + extension du Tumulus\u00a0!"}]},{"@type":"WebSite","@id":"http:\/\/baden-developpement.org\/#website","url":"http:\/\/baden-developpement.org\/","name":"Association Baden D\u00e9veloppement","description":"Demain se construit aujourd&#039;hui","publisher":{"@id":"http:\/\/baden-developpement.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/baden-developpement.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/baden-developpement.org\/#organization","name":"Association Baden D\u00e9veloppement","url":"http:\/\/baden-developpement.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/baden-developpement.org\/#\/schema\/logo\/image\/","url":"https:\/\/baden-developpement.org\/wp-content\/uploads\/2023\/09\/logo_abd_rc_tr.png","contentUrl":"https:\/\/baden-developpement.org\/wp-content\/uploads\/2023\/09\/logo_abd_rc_tr.png","width":1051,"height":623,"caption":"Association Baden D\u00e9veloppement"},"image":{"@id":"http:\/\/baden-developpement.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/baden-developpement.org\/#\/schema\/person\/8b73b426699bc182dc9f25bed1f1c8c1","name":"Denis Sempere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3cee0fe0e0dbe0a55cf3786d35daa256aa7a1b2802fe1a74406aebb920d6d763?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3cee0fe0e0dbe0a55cf3786d35daa256aa7a1b2802fe1a74406aebb920d6d763?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3cee0fe0e0dbe0a55cf3786d35daa256aa7a1b2802fe1a74406aebb920d6d763?s=96&d=mm&r=g","caption":"Denis Sempere"},"url":"https:\/\/baden-developpement.org\/index.php\/author\/denis\/"}]}},"_links":{"self":[{"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/posts\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/comments?post=756"}],"version-history":[{"count":2,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/posts\/756\/revisions"}],"predecessor-version":[{"id":762,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/posts\/756\/revisions\/762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/media\/759"}],"wp:attachment":[{"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/media?parent=756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/categories?post=756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/baden-developpement.org\/index.php\/wp-json\/wp\/v2\/tags?post=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}